{"id":5383,"date":"2025-12-19T14:39:15","date_gmt":"2025-12-19T13:39:15","guid":{"rendered":"https:\/\/www.informationskompetenz.de\/?p=5383"},"modified":"2026-01-12T11:21:17","modified_gmt":"2026-01-12T10:21:17","slug":"bericht-11-round-table-informationskompetenz-microlearning-am-09-12-2025-in-ilmenau","status":"publish","type":"post","link":"https:\/\/www.informationskompetenz.de\/index.php\/bericht-11-round-table-informationskompetenz-microlearning-am-09-12-2025-in-ilmenau\/","title":{"rendered":"Bericht: 11. Round Table Informationskompetenz \u201eMicrolearning\u201c am 09.12.2025 in Ilmenau"},"content":{"rendered":"<p>Der diesj\u00e4hrige Roundtable Informationskompetenz fand am Dienstag, den 9. Dezember 2025, in der Universit\u00e4tsbibliothek Ilmenau statt. Thematischer Schwerpunkt war Microlearning \u2013 ein Bereich, der im Kontext der Informationskompetenzvermittlung noch wenig beforscht ist, aber Potenziale birgt.<\/p>\n<h2>Informationskompetenz in Th\u00fcringen<\/h2>\n<p>Milena Pfafferoth begr\u00fc\u00dfte alle Teilnehmenden und stellte die IK-Aktivit\u00e4ten und -Netzwerke in Th\u00fcringen vor. Als Teil des Kooperationsverbunds Th\u00fcringer Hochschulen ist die <a href=\"https:\/\/thhobi.de\/bsc\/ag-informationskompetenz\" target=\"_blank\" rel=\"noopener\">BSC-AG Informationskompetenz (IK)<\/a> ein Netzwerk f\u00fcr den pers\u00f6nlichen Erfahrungsaustausch aller Th\u00fcringer Hochschulbibliotheken, der Forschungsbibliothek Gotha und der Herzogin Anna Amalia Bibliothek in Weimar zur \u201eInformationsvermittlung\u201c. Die starke regionale Vernetzung umfasst auch gemeinsame Arbeit an Standards und Richtlinien und zeigt, welche starke Synergien durch IK-Vernetzung entstehen k\u00f6nnen (<a href=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/20251209_pfafferott_IKTH.pdf\">Folien<\/a>).<\/p>\n<h2>Microlearning \u2013 Definition, Hintergr\u00fcnde, Formate (Christina Schmitz, Timo Steyer)<\/h2>\n<p>Der Einf\u00fchrungsvortrag (<a href=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/PPT_microlearning_251209_public.pdf\">Folien<\/a>) von Christina Schmitz (Staatsbibliothek zu Berlin) und Timo Steyer (Universit\u00e4tsbibliothek Braunschweig) bot erste begriffliche Ann\u00e4herungsversuche. Der Begriff ist schillernd, und was unter Microlearning f\u00e4llt, ist nicht abschlie\u00dfend definiert. Man denkt beim Gebrauch des Wortes zun\u00e4chst an didaktische Kurzformate wie Lernkarten, Wissensh\u00e4ppchen, Coffee Lectures, Schulungseinheiten in Lern-Apps, digitale Schnitzeljagden oder QR-Codes, die auf Kurzinformationen verweisen. Insbesondere sind damit aber Formen der Kommunikation in den sozialen Medien gemeint, in denen grafisch attraktiv aufbereiteter Content in wenigen S\u00e4tzen \u00fcbermittelt wird.<\/p>\n<p>Diese Lernformate entsprechen den ge\u00e4nderten Lernbedarfen der Studierenden: Klassische Vor-Ort-Workshops werden zunehmend weniger nachgefragt, w\u00e4hrend \u201eJust-in-Time\u201c-Inhalte st\u00e4rker im Fokus stehen. Die Studierenden fordern mehr als zuvor Informationen zu orts- und zeitabh\u00e4ngig auftretenden Problemen. Daten der <a href=\"https:\/\/mpfs.de\/studie\/jim-studie-2025\/\" target=\"_blank\" rel=\"noopener\">JIM-Studie 2025<\/a> zur Mediennutzung von Sch\u00fcler:innen zeigen, dass \u201eJust-in-Time\u201c-Formate ihnen l\u00e4ngst vertraut sind und zu ihren Informationsgewohnheiten passen. Microlearning wird in Zukunft diese Bedarfe bedienen und bestehende Langformate erg\u00e4nzen k\u00f6nnen. Typische Einsatzgebiete wurden von allen Teilnehmenden \u2013 auch den kritisch Nachfragenden \u2013 in der Vor- und Nachbereitung von Lernereignissen sowie im Training au\u00dferhalb eines eigentlichen Lernkontextes gesehen.<\/p>\n<p>Ein Grundgedanke des Microlearnings ist, Lernformate st\u00e4rker an die Umgebungen anzupassen, in denen sich Lernende ohnehin aufhalten. Gleichzeitig ver\u00e4ndert sich die Vermittlungslogik: weg vom Push-Prinzip, hin zu Pull-Angeboten, die bei Bedarf selbst abgerufen werden. Gamification, der Einsatz von Podcasts oder Lernvideos lassen sich in diese Logik bestens einbetten, weil sie Inhalte spielerisch vermitteln und mit dem eigenen Endger\u00e4t von \u00fcberall abgerufen werden k\u00f6nnen. Ohnehin spielt die Devise \u201eBring Your Own Device\u201c eine gewichtige Rolle im Microlearning \u2013 verbunden mit der wachsenden Bedeutung der Individualisierung und Personalisierung von Lerninhalten. Microlearning zahlt damit auf den Trend des selbstgesteuerten Lernens ein. Besonders beliebt sind visuelle, einfach strukturierte Formate, oft kombiniert mit Belohnungssystemen oder Empfehlungslogiken (\u201eNutzer:innen, die diesen Content interessant fanden auch diesen Content interessant&#8220;).<\/p>\n<h3>Herausforderungen<\/h3>\n<p>Trotz der vielen Potenziale wurden auch die Schwierigkeiten sichtbar:<\/p>\n<ul>\n<li>Lerneinheiten m\u00fcssen in sich abgeschlossen sein und gleichzeitig in der Summe eine inhaltliche Klammer bilden \u2013 eine anspruchsvolle konzeptionelle Aufgabe.<\/li>\n<li>Interaktive Elemente erh\u00f6hen zwar die Attraktivit\u00e4t, sind aber kosten- und entwicklungsintensiv, wenn sie durch Eigenentwicklungen integriert werden sollen.<\/li>\n<li>Wird auf kommerzielle Plattformen zur\u00fcckgegriffen, entsteht eine Abh\u00e4ngigkeit von Konzernen, die auf verschiedenen Ebenen problematisch werden kann \u2013 wie das Beispiel von X (ehem. Twitter) zeigt.<\/li>\n<li>Offen bleibt, welche Lernziele mit granularen Formaten erreicht werden k\u00f6nnen und an welchen Stellen die didaktische Langstrecke unverzichtbar ist.<\/li>\n<\/ul>\n<h3>Diskussion<\/h3>\n<p>In der anschlie\u00dfenden Diskussion wurde u. a. die Frage aufgeworfen, welche Rolle Microlearning in Feldern wie Demokratiebildung, Gemeinschaft oder gesellschaftlichem Zusammenhalt spielen kann. Bibliotheken haben hier einen politischen und sozialen Auftrag \u2013 ob und wie Microlearning diesen unterst\u00fctzen kann, blieb offen.<br \/>\nReflektiert werden sollte, welche Lernziele sich \u00fcberhaupt mit Microlearning erreichen lassen \u2013 und welche nicht. W\u00e4hrend die Methoden des Microlearning zur reinen Informationsvermittlung sicher gute Ans\u00e4tze bieten, ist der Erwerb von Kompetenzen und das Erlernen einer Praxis zeitintensiv und auf Wiederholungen angewiesen.<\/p>\n<h2>Jana Dreston (Universit\u00e4t Duisburg-Essen): Informeller Wissenserwerb \u00fcber soziale Medien<\/h2>\n<p>Der zweite Vortrag von <a href=\"https:\/\/www.uni-due.de\/media-psych-edu\/dreston_cv\" target=\"_blank\" rel=\"noopener\">Jana Dreston<\/a> lieferte hierzu zentrale Hinweise (<a href=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/InformationskompetenzDreston_gekuerzt.pdf\">Folien<\/a>). Mit Verweis auf ihre eigenen lernpsychologischen Untersuchungen spannte sie einen theoretischen Rahmen auf, in dem sie Antworten auf die Frage formulierte, welche Bedingungen zum Erzielen eines Lernerfolgs erf\u00fcllt sein m\u00fcssen. Ihr Fokus lag dabei auf Microlearning und informellem Lernen \u00fcber soziale Medien.<br \/>\nEin zentrales Ergebnis ihrer Untersuchungen: Klassische Vermittlungsformate sind nicht automatisch \u00fcberlegen. Im Gegenteil \u2013 unter bestimmten Bedingungen erinnern sich Menschen besser an Inhalte, die sie z. B. auf Instagram konsumieren. Entscheidend ist nicht das Medium, sondern ob<\/p>\n<ul>\n<li>man die Inhalte auch nutzt (Inhalte \u201eelaboriert\u201c),<\/li>\n<li>man Inhalte aktiv (also \u201eintentional\u201c) aufsucht,<\/li>\n<li>Inhalte als bedeutsam (\u201erelevant\u201c) empfunden werden.<\/li>\n<\/ul>\n<p>Sind diese Voraussetzungen erf\u00fcllt, kann Lernen auch im Mikroformat sehr effektiv sein. Ein Experiment, das Dreston vorstellte, dokumentierte dies eindr\u00fccklich: Die Probanden erhielten Informationen \u00fcber ein Thema \u00fcber einen klassischen Newsletter, \u00fcber Instagram-Stories ohne Mitmachelemente oder \u00fcber Instagram mit aktiven sog. Elaborationsanreizen (Fragen beantworten, Vorwissen aktivieren, Nachdenken ausl\u00f6sen; auch die Nutzung der Kommentarspalte kann als Elaborationsaktivit\u00e4t angesehen werden).<\/p>\n<ul>\n<li>Ohne Elaborationsanreize schnitten Social-Media-Formate schlechter ab als der Newsletter.<\/li>\n<li>Mit Elaborationsanreizen f\u00fchrten Social-Media-Formate dagegen zum besten Lernerfolg.<\/li>\n<\/ul>\n<p>Die Ergebnisse weisen darauf hin, dass mehr die Art der Aufnahme als die Form der Pr\u00e4sentation des Wissens \u00fcber Lernerfolg entscheidet.<\/p>\n<p>Ein zweiter messbarer Faktor ist, ob Menschen Inhalte gezielt suchen (intentional) oder ihnen zuf\u00e4llig begegnen (inzidentell). Arten der inzidentellen Informationsaufnahme sind uns aus dem Alltag bekannt, z. B. Infoscreens in der U-Bahn. Interessant war eine in diesem Rahmen vorgestellte Studie, der zufolge inzidenteller Kontakt Wissensunterschiede verringern kann. Das Allgemeinwissen von Menschen mit wenig Vorwissen n\u00e4hert sich bei zuf\u00e4llig konsumierten Inhalten demnach dem Kenntnisstand von Personen an, die von vornherein \u00fcber eine hohe Allgemeinbildung verf\u00fcgen.<br \/>\nIm Falle des Lernens durch soziale Medien begeben wir uns auf dem Spektrum zwischen zuf\u00e4lliger und bewusst gesteuerter Informationsaufnahme in einen Zwischenbereich. Zwar werden algorithmische Anpassungen der Inhalte an User-Interessen automatisch vorgenommen. Aber viele Nutzer:innen beeinflussen Feeds und Vorschlagslisten bewusst dadurch, dass sie bestimmte Inhalte blockieren oder interessante liken. Sie \u201etrainieren\u201c oder \u201epflegen\u201c ihren Algorithmus.<\/p>\n<h3>Fazit<\/h3>\n<p>Insgesamt erzwangen Drestons Ausf\u00fchrungen eine differenzierte Sichtweise des (Mikro-)Learnings mit sozialen Medien. Die Portionierung und Digitalisierung von Lerninhalten f\u00fchrt zwar nicht zu Misserfolg im Lernen, aber andererseits k\u00f6nnen wir sperrige Stoffe nicht allein dadurch an die Lernenden bringen, dass wir eine Insta-Story draus machen. Die User sind derweil weder nur gestaltend, noch werden sie vom Content ungefragt \u00fcberw\u00e4ltigt. Die Wahrheit liegt wie so oft dazwischen.<\/p>\n<h3>Was hei\u00dft das nun f\u00fcr Bibliotheken?<\/h3>\n<p>Drestons zentrale Aussage, dass ein selbstt\u00e4tig elaborierter, aktiv aufgesuchter und als bedeutsam erkannter Inhalt zu maximalem Lernerfolg f\u00fchrt, macht meiner Meinung nach Hoffnung f\u00fcr die Bibliotheken. Alle drei Bedingungen sind in Bibliotheken schon dann erf\u00fcllt, wenn Nutzer:innen mit einer konkreten Frage aktiv zu uns kommen: Sie haben eine klare Absicht und wenden die Kenntnisse \u00fcber den Bestand in der Lernumgebung an. Unsere Aufgabe ist es also vor allem, diese guten Voraussetzungen durch passende Formate abzuholen \u2013 auch im Microlearning-Bereich. (c) Malte Dreyer<\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%;\"><a href=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/ml_gruppe1_md.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5384 size-thumbnail alignleft\" title=\"(c) Malte Dreyer\" src=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/ml_gruppe1_md-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><a href=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/ml_gruppe2_md.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5385 size-thumbnail alignleft\" src=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/ml_gruppe2_md-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><a href=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/ml_gruppe3_md.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5386 size-thumbnail alignleft\" src=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/ml_gruppe3_md-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><a href=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/ml_gruppe4_md.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5387 size-thumbnail alignleft\" title=\"(c) Malte Dreyer\" src=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/ml_gruppe4_md-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Bilder Worlcaf\u00e9 1: Microlearning, (c) Malte Dreyer<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>World Caf\u00e9: Neue Themen und Formate im IK-Bereich<\/h2>\n<p>Zum Abschluss des Roundtables fand ein World Caf\u00e9 statt, bei dem Themen aus dem Plenum in Kleingruppen bearbeitet wurden. Eine von mir moderierte Gruppe besch\u00e4ftigte sich mit neuen Themen und Formaten in der Informationskompetenz.<\/p>\n<ul>\n<li><strong>Neue Themenfelder: KI als Querschnittsthema<\/strong><br \/>\nSchnell wurde deutlich, dass K\u00fcnstliche Intelligenz derzeit das zentrale Oberthema ist. Die Gruppe war sich einig, dass KI nicht nur ein zus\u00e4tzliches Thema darstellt, sondern in alle bestehenden IK-Formate integriert werden sollte. Der Anpassungsbedarf ist entsprechend gro\u00df. Generell gilt dabei: Die mit dem Einzug von KI verbundenen ethischen, fachlichen und politischen Implikationen m\u00fcssen auch und insbesondere in Bibliotheken systematisch erschlossen werden. Ohne ein derartiges Begleitprogramm geraten Aktivit\u00e4ten an der Basis in Gefahr, ihre Richtung zu verlieren.<br \/>\nEin zweiter allgemeiner Punkt betraf die zielgruppenspezifische Anpassung. Unterschiedliche Zielgruppen bringen unterschiedliche Voraussetzungen mit, was die Konzeption von Formaten anspruchsvoll macht. Zugleich bietet das aber Potenziale: Manche Kurse, die bisher f\u00fcr bestimmte Niveaus konzipiert wurden, k\u00f6nnten so umgestaltet werden, dass sie auch f\u00fcr andere Anspruchsniveaus funktionieren. Das schafft Synergien im eigenen Haus.<\/li>\n<li><strong>Formate \u2013 Altbekanntes reaktivieren und Neues denken<\/strong><br \/>\nIn der Diskussion tauchten einige Formate wieder auf, die vielerorts etwas in Vergessenheit geraten sind, aber anderswo weiterhin sehr gut funktionieren: Kandidaten f\u00fcr aussichtsreiche Wiederbelebungsversuche. Dazu geh\u00f6ren Poster und E-Learning-Kurse. Ein bemerkenswerter Aufruf aus einer Nachbargruppe lie\u00df indes aufhorchen: \u201eLasst uns endlich wieder richtig geile Newsletter machen!!!\u201c Das kann man einfach mal so stehen lassen.<br \/>\nEin weiterer Schwerpunkt war die Frage, wie sich die Schnittstelle zwischen Pausen- und Arbeitszeit besser bespielen l\u00e4sst. Viele Einrichtungen haben ihre Coffee Lectures und Brown-Bag-Lunches reduziert oder abgeschafft. Hier wurde \u00fcber m\u00f6gliche Alternativen nachgedacht. Eine Kollegin platzierte so bedeutungsvoll wie offen eine Karte mit dem Wort \u201eGamification\u201c im entsprechenden Bereich des Whiteboards.<br \/>\nBei der Frage, welche innovativen Inhalte umgesetzt werden k\u00f6nnten, wurden Beispiele aus der Praxis genannt, darunter: Kurse zum Erstellen eines Podcasts, Veranstaltungen zu Open Science, zur Quellenkritik oder Formate zur Guten wissenschaftlichen Praxis.<br \/>\nF\u00fcr unsere eigene Einrichtung ergeben sich daraus wertvolle Hinweise \u2013 insbesondere als Erg\u00e4nzung zu bestehenden Angeboten wie den Literaturrecherche-Kursen, die ohnehin im Zuge der KI-Entwicklungen aktualisiert werden m\u00fcssen.<\/li>\n<\/ul>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%;\"><a href=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/bc_gruppe1_md.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-5391 alignleft\" src=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/bc_gruppe1_md-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/bc_gruppe2_md.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-5392 alignleft\" src=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/bc_gruppe2_md-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/bc_gruppe3_md.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-5393 alignleft\" src=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/bc_gruppe3_md-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><a href=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/bc_gruppe4_sar.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-5394 alignleft\" src=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/bc_gruppe4_sar-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/bc_gruppe5_sar.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-5395 alignleft\" src=\"https:\/\/www.informationskompetenz.de\/wp-content\/uploads\/2025\/12\/bc_gruppe5_sar-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Bilder Worldcaf\u00e8 2: Ausgew\u00e4hlte IK-Themen, 1-3 (c) Malte Dreyer, 4-5 (c) Sabine Rauchmann<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Fazit<\/h2>\n<p>Insgesamt beeindruckte das World Caf\u00e9 \u2013 wie der gesamte Roundtable \u2013 durch das sehr agile Umfeld und bot inspirierende Impulse f\u00fcr die Weiterentwicklung der Informationskompetenzvermittlung. Viele Ideen waren direkt auf die eigene Praxis \u00fcbertragbar und boten konkrete Ansatzpunkte, um bestehende Formate weiterzuentwickeln oder neue Schwerpunkte zu setzen. Ideen, die wir in den kommenden Monaten und Jahren gut gebrauchen k\u00f6nnen.<\/p>\n<p>&#8212;<\/p>\n<p>Autor: <a href=\"https:\/\/www.sub.uni-goettingen.de\/kontakt\/personen-a-z\/personendetails\/person\/malte-dreyer\/\" target=\"_blank\" rel=\"noopener\">Dr. Malte Dreyer<\/a>, Nieders\u00e4chsische Staats- und Universit\u00e4tsbibliothek G\u00f6ttingen<br \/>\nRedaktionelle Bearbeitung: Sabine Rauchmann, Gemeinsame Kommission Informationskompetenz von dbv und VDB<\/p>\n<p>&#8212;<\/p>\n<p>Erkl\u00e4rung zur Nutzung von ChatGPT und vergleichbaren Werkzeugen: In dem hier vorliegenden Text habe ich ChatGPT oder eine andere KI wie folgt genutzt:<br \/>\n[ ] gar nicht<br \/>\n[ ] bei der Ideenfindung<br \/>\n[ ] bei der Erstellung der Gliederung<br \/>\n[ ] zum Erstellen einzelner Passagen, insgesamt im Umfang von \u2026% am gesamten Text<br \/>\n[ ] zur Entwicklung von Software-Quelltexten<br \/>\n[ ] zur Optimierung oder Umstrukturierung von Software-Quelltexten<br \/>\n[x] zum Korrekturlesen<br \/>\n[x] Weiteres, n\u00e4mlich: zum Ausformulieren einzelner Passagen nach einer Vorlage aus Stichpunkten und Notizen. Der daraufhin entstandene Text wurde vollst\u00e4ndig \u00fcberarbeitet und restrukturiert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der diesj\u00e4hrige Roundtable Informationskompetenz fand am Dienstag, den 9. Dezember 2025, in der Universit\u00e4tsbibliothek Ilmenau statt. Thematischer Schwerpunkt war Microlearning \u2013 ein Bereich, der im Kontext der Informationskompetenzvermittlung noch wenig [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[55,145],"class_list":["post-5383","post","type-post","status-publish","format-standard","hentry","category-kommission","tag-round-table","tag-roundtable-ik-2025"],"_links":{"self":[{"href":"https:\/\/www.informationskompetenz.de\/index.php\/wp-json\/wp\/v2\/posts\/5383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.informationskompetenz.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.informationskompetenz.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.informationskompetenz.de\/index.php\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/www.informationskompetenz.de\/index.php\/wp-json\/wp\/v2\/comments?post=5383"}],"version-history":[{"count":11,"href":"https:\/\/www.informationskompetenz.de\/index.php\/wp-json\/wp\/v2\/posts\/5383\/revisions"}],"predecessor-version":[{"id":5415,"href":"https:\/\/www.informationskompetenz.de\/index.php\/wp-json\/wp\/v2\/posts\/5383\/revisions\/5415"}],"wp:attachment":[{"href":"https:\/\/www.informationskompetenz.de\/index.php\/wp-json\/wp\/v2\/media?parent=5383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.informationskompetenz.de\/index.php\/wp-json\/wp\/v2\/categories?post=5383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.informationskompetenz.de\/index.php\/wp-json\/wp\/v2\/tags?post=5383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}